{"id":4492,"date":"2026-04-21T15:55:37","date_gmt":"2026-04-21T15:55:37","guid":{"rendered":"https:\/\/incentea.com\/pt\/?p=4492"},"modified":"2026-04-29T16:13:54","modified_gmt":"2026-04-29T16:13:54","slug":"22a-convencao-incentea","status":"publish","type":"post","link":"https:\/\/incentea.com\/pt\/22a-convencao-incentea\/","title":{"rendered":"22\u00aa Conven\u00e7\u00e3o INCENTEA"},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; left_padding_desktop=&#8221;15%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;15%&#8221; left_padding_tablet=&#8221;0%&#8221; constrain_group_4=&#8221;yes&#8221; right_padding_tablet=&#8221;0%&#8221; left_padding_phone=&#8221;0%&#8221; constrain_group_6=&#8221;yes&#8221; right_padding_phone=&#8221;0%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;4493&#8243; image_size=&#8221;large&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;20px&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;5%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;5%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h2>Conven\u00e7\u00e3o INCENTEA 2026 refor\u00e7a vis\u00e3o, cultura e ambi\u00e7\u00e3o para o futuro.<\/h2>\n[\/vc_column_text][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<span style=\"color: #233dec;\">A INCENTEA realizou a sua Conven\u00e7\u00e3o 2026, um dos momentos mais marcantes do calend\u00e1rio interno da organiza\u00e7\u00e3o, reunindo colaboradores, parceiros e clientes num encontro que refor\u00e7ou a import\u00e2ncia das pessoas, da vis\u00e3o partilhada e da ambi\u00e7\u00e3o estrat\u00e9gica que tem orientado o crescimento da empresa. O evento voltou a demonstrar que as grandes organiza\u00e7\u00f5es n\u00e3o se constroem apenas com tecnologia, estrat\u00e9gia ou resultados, mas sobretudo com equipas alinhadas por um prop\u00f3sito comum.<br \/>\n<\/span>[\/vc_column_text][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]Conduzida pelo Board Member Lu\u00eds Barreiro, a sess\u00e3o destacou uma INCENTEA mais ambiciosa na conquista do mercado ib\u00e9rico, mais internacional pela consolida\u00e7\u00e3o nos mercados lus\u00f3fonos e cada vez mais preparada para liderar a transforma\u00e7\u00e3o digital dos seus clientes.<br \/>\nEntre os marcos apresentados estiveram opera\u00e7\u00f5es estrat\u00e9gicas que refor\u00e7aram a presen\u00e7a internacional da empresa, como a aquisi\u00e7\u00e3o da F3M Angola, que ampliou a capacidade de atua\u00e7\u00e3o no mercado angolano com foco nas solu\u00e7\u00f5es Cegid, a integra\u00e7\u00e3o da Dragomar em Espanha, a entrada no capital da Kaizen Tech, refor\u00e7ando a aposta em solu\u00e7\u00f5es industriais para empresas de maior dimens\u00e3o.<br \/>\nA Conven\u00e7\u00e3o evidenciou tamb\u00e9m o investimento cont\u00ednuo em inova\u00e7\u00e3o, com destaque para iniciativas na \u00e1rea da Intelig\u00eancia Artificial e para novas solu\u00e7\u00f5es de seguran\u00e7a desenvolvidas internamente, alinhadas com referenciais como a ISO 27001. Estas solu\u00e7\u00f5es permitem aos clientes implementar medidas de prote\u00e7\u00e3o de forma modular e progressiva, refor\u00e7ando a maturidade tecnol\u00f3gica das organiza\u00e7\u00f5es.<br \/>\nA evolu\u00e7\u00e3o da INCENTEA tamb\u00e9m se traduz em n\u00fameros: 369 colaboradores, 36.000 horas de forma\u00e7\u00e3o em 2025 e uma presen\u00e7a geogr\u00e1fica distribu\u00edda entre Portugal, mercados internacionais e colaboradores em regime digital. Lu\u00eds Barreiro sublinhou ainda a transi\u00e7\u00e3o da INCENTEA para o segmento Small Midcap, integrando um grupo restrito de cerca de 300 empresas em Portugal. [\/vc_column_text][nectar_single_testimonial testimonial_style=&#8221;small_modern&#8221; text_color=&#8221;#233DEC&#8221; color=&#8221;Default&#8221; quote=&#8221;O futuro n\u00e3o \u00e9 algo que acontece de repente. O futuro constr\u00f3i-se.&#8221; name=&#8221;Lu\u00eds Barreiro&#8221; subtitle=&#8221;Board Member da INCENTEA&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]A cultura organizacional esteve tamb\u00e9m em destaque com a iniciativa INCENTEA Move Together, que promove h\u00e1bitos de vida saud\u00e1veis, caminhadas, dicas de nutri\u00e7\u00e3o e momentos de liga\u00e7\u00e3o genu\u00edna, contribuindo para o bem\u2011estar e para a redu\u00e7\u00e3o do stress no dia a dia.<br \/>\nUm dos momentos mais simb\u00f3licos da Conven\u00e7\u00e3o foi a homenagem \u00e0 empresa Caiado, cliente hist\u00f3rico da INCENTEA. A distin\u00e7\u00e3o, entregue por Filipe Fonseca, celebrou uma rela\u00e7\u00e3o constru\u00edda com confian\u00e7a e proximidade ao longo de d\u00e9cadas. \u201cO Caiado faz parte da hist\u00f3ria da INCENTEA e se calhar n\u00f3s tamb\u00e9m da hist\u00f3ria do Caiado\u201d, afirmou. Em resposta, Paula Caiado refor\u00e7ou o esp\u00edrito de continuidade: \u201cVamos tentar continuar por mais 50 anos.\u201d<br \/>\nA interven\u00e7\u00e3o do keynote speaker Ricardo Cabete, especialista em Intelig\u00eancia Emocional, trouxe mensagens de inspira\u00e7\u00e3o e reflex\u00e3o, sublinhando o impacto que pequenas mudan\u00e7as de atitude podem ter no desempenho individual e coletivo.<br \/>\nNa mensagem de encerramento, o CEO e Board Member Ant\u00f3nio Po\u00e7as agradeceu o esfor\u00e7o conjunto, refor\u00e7ou a cultura de melhoria cont\u00ednua e destacou o papel da ambi\u00e7\u00e3o no crescimento da INCENTEA. Para os pr\u00f3ximos anos os objetivos da empresa passam por duplicar a fatura\u00e7\u00e3o e rentabilidade, aumentar a efici\u00eancia e refor\u00e7ar a presen\u00e7a em clientes Corporate. Sobre Intelig\u00eancia Artificial, deixou uma das mensagens mais marcantes do evento:[\/vc_column_text][nectar_single_testimonial testimonial_style=&#8221;small_modern&#8221; text_color=&#8221;#233DEC&#8221; color=&#8221;Default&#8221; quote=&#8221;Queremos ser uma empresa mais tecnol\u00f3gica, mas isso n\u00e3o quer dizer que n\u00e3o queiramos continuar a ser uma empresa muito humana.&#8221; name=&#8221;Ant\u00f3nio Po\u00e7as&#8221; subtitle=&#8221;CEO e Board Member da INCENTEA&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]Recordou ainda o epis\u00f3dio da tempestade em Leiria, destacando a resili\u00eancia e entreajuda demonstradas pela equipa, num momento que refletiu a for\u00e7a da cultura interna.<br \/>\nMais do que um encontro anual, a Conven\u00e7\u00e3o INCENTEA 2026 afirmou\u2011se como um momento de alinhamento estrat\u00e9gico e de refor\u00e7o da cultura organizacional, fortalecendo a liga\u00e7\u00e3o entre colaboradores, parceiros e clientes. A edi\u00e7\u00e3o deste ano evidencia uma INCENTEA em crescimento, que continua a evoluir sem perder aquilo que a distingue: proximidade, confian\u00e7a e um foco genu\u00edno nas pessoas.<\/p>\n<p><strong>O que marcou esta edi\u00e7\u00e3o?<\/strong><br \/>\n<strong><span style=\"color: #233dec;\">Cultura forte. Ambiente genu\u00edno.<\/span><\/strong>[\/vc_column_text][nectar_video_lightbox link_style=&#8221;play_button_2&#8243; nectar_play_button_color=&#8221;Default-Accent-Color&#8221; image_url=&#8221;4495&#8243; hover_effect=&#8221;defaut&#8221; box_shadow=&#8221;none&#8221; border_radius=&#8221;20px&#8221; play_button_size=&#8221;default&#8221; video_url=&#8221;https:\/\/www.youtube.com\/watch?v=2JuR3eOAL9Q&#8221;][nectar_btn size=&#8221;small&#8221; open_new_tab=&#8221;true&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Accent-Color&#8221; solid_text_color_override=&#8221;#FFFFFF&#8221; icon_family=&#8221;none&#8221; el_class=&#8221;button-blue-bullet&#8221; text=&#8221;Assista \u00e0 grava\u00e7\u00e3o do evento&#8221; url=&#8221;https:\/\/www.youtube.com\/live\/QbNY2pTh9Y8?si=MYFVSVJNTbZvbJsL&amp;t=6602&#8243; margin_top=&#8221;30&#8243; margin_bottom=&#8221;40&#8243;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<strong>A INCENTEA agradece a presen\u00e7a de todos os colaboradores, parceiros e clientes que participaram na 22.\u00aa edi\u00e7\u00e3o da Conven\u00e7\u00e3o, refor\u00e7ando rela\u00e7\u00f5es de confian\u00e7a essenciais ao crescimento conjunto.<\/strong><br \/>\nCILIS, BCP, Bourbon Automotive Plastics Marinha Grande AS, BuildUpValue, Caiado, CBRE, Cegid, Cleanwatts, Cubo Drive, S.A., Embalagem do Futuro, Filedoc, Forvis Mazars, Glose, Hornetsecurity, HPE, Humangext, Iberoalpla Portugal, lda, Innov3D Lda, Itancia, JLM &#8211; Consultores de Gest\u00e3o, Lda., Kaizen Tech, Leadzai, Lubrigaz, Luz Sa\u00fade, Media Gate, MedicineOne, Mercatura, Tecnologias de Informacao Lda, Millennium BCP, Moneris, Moving2U, Lda., NERLEI CCI, Novo Banco, NYV Capital, Polit\u00e9cnico de Leiria, PR Gate, Primavera, Ra\u00e7\u00f5es Z\u00eazere, S.A., RRgest, Lda, Sage, Sisqual, TD SYNNEX, Tranquilidade e Winsig.[\/vc_column_text][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<strong>Veja alguns dos highlights deste evento<\/strong>[\/vc_column_text][vc_gallery css=&#8221;.vc_custom_1776770146489{border-radius: 30px !important;}&#8221; type=&#8221;image_grid&#8221; images=&#8221;4500,4501,4502,4503,4504,4505,4506,4509,4510,4508,4511,4507,4512,4513,4514,4515&#8243; image_grid_loading=&#8221;default&#8221; layout=&#8221;4&#8243; item_spacing=&#8221;default&#8221; gallery_style=&#8221;7&#8243; load_in_animation=&#8221;none&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;5%&#8221; left_padding_desktop=&#8221;5%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;5%&#8221; left_padding_tablet=&#8221;0%&#8221; constrain_group_4=&#8221;yes&#8221; right_padding_tablet=&#8221;0%&#8221; left_padding_phone=&#8221;0%&#8221; constrain_group_6=&#8221;yes&#8221; right_padding_phone=&#8221;0%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;bottom&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;3\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_col-xs-12&#8243;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h2>Tamb\u00e9m poder\u00e1 ter interesse<\/h2>\n[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_hidden-sm vc_hidden-xs&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;center&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221; delay=&#8221;250&#8243; offset=&#8221;vc_col-xs-12&#8243;][nectar_btn size=&#8221;medium&#8221; open_new_tab=&#8221;true&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Accent-Color&#8221; solid_text_color_override=&#8221;#FFFFFF&#8221; icon_family=&#8221;none&#8221; el_class=&#8221;button-blue-bullet&#8221; text=&#8221;Ver mais&#8221; url=&#8221;\/pt\/noticias&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;3%&#8221; constrain_group_2=&#8221;yes&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][nectar_post_grid post_type=&#8221;post&#8221; blog_category=&#8221;all&#8221; blog_starting_category=&#8221;all&#8221; order=&#8221;DESC&#8221; orderby=&#8221;date&#8221; pagination=&#8221;none&#8221; columns=&#8221;3&#8243; columns_tablet=&#8221;default&#8221; columns_phone=&#8221;default&#8221; grid_item_spacing=&#8221;25px&#8221; grid_item_height=&#8221;30vh&#8221; 3_col_masonry_layout=&#8221;default&#8221; image_size=&#8221;medium&#8221; image_loading=&#8221;default&#8221; animation=&#8221;none&#8221; animation_stagger=&#8221;90&#8243; animation_easing=&#8221;default&#8221; heading_tag=&#8221;default&#8221; heading_tag_render=&#8221;default&#8221; display_categories=&#8221;yes&#8221; category_functionality=&#8221;static&#8221; category_position=&#8221;overlaid&#8221; category_style=&#8221;underline&#8221; category_display=&#8221;default&#8221; display_date=&#8221;yes&#8221; additional_meta_size=&#8221;default&#8221; custom_fields_location=&#8221;after_post_meta&#8221; grid_style=&#8221;content_under_image&#8221; card_design=&#8221;yes&#8221; card_bg_color=&#8221;#F5F5F5&#8243; content_under_image_text_align=&#8221;left&#8221; text_color=&#8221;light&#8221; hover_effect=&#8221;animated_underline&#8221; border_radius=&#8221;20px&#8221; display_type=&#8221;grid&#8221; posts_per_page=&#8221;3&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_margin_phone=&#8221;12%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_global_section id=&#8221;120&#8243;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; left_padding_desktop=&#8221;15%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;15%&#8221; left_padding_tablet=&#8221;0%&#8221; constrain_group_4=&#8221;yes&#8221; right_padding_tablet=&#8221;0%&#8221; left_padding_phone=&#8221;0%&#8221; constrain_group_6=&#8221;yes&#8221; right_padding_phone=&#8221;0%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221;&#8230;<\/p>\n","protected":false},"author":4,"featured_media":4493,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[24,32,25],"tags":[],"class_list":{"0":"post-4492","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-eventos","8":"category-noticias","9":"category-pessoas"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>22\u00aa Conven\u00e7\u00e3o INCENTEA<\/title>\n<meta name=\"description\" content=\"A INCENTEA voltou a provar, em 2026, que grandes empresas n\u00e3o se constroem apenas com estrat\u00e9gia, tecnologia ou resultados. Constroem-se com pessoas alinhadas pela mesma vis\u00e3o.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/incentea.com\/pt\/22a-convencao-incentea\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"22\u00aa Conven\u00e7\u00e3o INCENTEA\" \/>\n<meta property=\"og:description\" content=\"A INCENTEA voltou a provar, em 2026, que grandes empresas n\u00e3o se constroem apenas com estrat\u00e9gia, tecnologia ou resultados. Constroem-se com pessoas alinhadas pela mesma vis\u00e3o.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/incentea.com\/pt\/22a-convencao-incentea\/\" \/>\n<meta property=\"og:site_name\" content=\"INCENTEA Portugal\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/incentea\/?locale=pt_PT\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-21T15:55:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-29T16:13:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/incentea.com\/pt\/wp-content\/uploads\/sites\/3\/2026\/04\/INCENTEA_artigo-convencao.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"937\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"luisferreira\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"luisferreira\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/incentea.com\\\/pt\\\/22a-convencao-incentea\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/incentea.com\\\/pt\\\/22a-convencao-incentea\\\/\"},\"author\":{\"name\":\"luisferreira\",\"@id\":\"https:\\\/\\\/incentea.com\\\/pt\\\/#\\\/schema\\\/person\\\/884fe8f51425a46e0eb1dec54cb42329\"},\"headline\":\"22\u00aa Conven\u00e7\u00e3o INCENTEA\",\"datePublished\":\"2026-04-21T15:55:37+00:00\",\"dateModified\":\"2026-04-29T16:13:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/incentea.com\\\/pt\\\/22a-convencao-incentea\\\/\"},\"wordCount\":2885,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/incentea.com\\\/pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/incentea.com\\\/pt\\\/22a-convencao-incentea\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/incentea.com\\\/pt\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2026\\\/04\\\/INCENTEA_artigo-convencao.webp\",\"articleSection\":[\"Eventos\",\"Noticias\",\"Pessoas\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/incentea.com\\\/pt\\\/22a-convencao-incentea\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/incentea.com\\\/pt\\\/22a-convencao-incentea\\\/\",\"url\":\"https:\\\/\\\/incentea.com\\\/pt\\\/22a-convencao-incentea\\\/\",\"name\":\"22\u00aa Conven\u00e7\u00e3o INCENTEA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/incentea.com\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/incentea.com\\\/pt\\\/22a-convencao-incentea\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/incentea.com\\\/pt\\\/22a-convencao-incentea\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/incentea.com\\\/pt\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2026\\\/04\\\/INCENTEA_artigo-convencao.webp\",\"datePublished\":\"2026-04-21T15:55:37+00:00\",\"dateModified\":\"2026-04-29T16:13:54+00:00\",\"description\":\"A INCENTEA voltou a provar, em 2026, que grandes empresas n\u00e3o se constroem apenas com estrat\u00e9gia, tecnologia ou resultados. Constroem-se com pessoas alinhadas pela mesma vis\u00e3o.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/incentea.com\\\/pt\\\/22a-convencao-incentea\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/incentea.com\\\/pt\\\/22a-convencao-incentea\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/incentea.com\\\/pt\\\/22a-convencao-incentea\\\/#primaryimage\",\"url\":\"https:\\\/\\\/incentea.com\\\/pt\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2026\\\/04\\\/INCENTEA_artigo-convencao.webp\",\"contentUrl\":\"https:\\\/\\\/incentea.com\\\/pt\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2026\\\/04\\\/INCENTEA_artigo-convencao.webp\",\"width\":1500,\"height\":937},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/incentea.com\\\/pt\\\/22a-convencao-incentea\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/incentea.com\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"22\u00aa Conven\u00e7\u00e3o INCENTEA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/incentea.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/incentea.com\\\/pt\\\/\",\"name\":\"INCENTEA Portugal\",\"description\":\"Website da INCENTEA em PORTUGAL\",\"publisher\":{\"@id\":\"https:\\\/\\\/incentea.com\\\/pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/incentea.com\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/incentea.com\\\/pt\\\/#organization\",\"name\":\"INCENTEA - PORTUGAL\",\"url\":\"https:\\\/\\\/incentea.com\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/incentea.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/incentea.com\\\/pt\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/09\\\/incentea_logo.svg\",\"contentUrl\":\"https:\\\/\\\/incentea.com\\\/pt\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/09\\\/incentea_logo.svg\",\"width\":251,\"height\":41,\"caption\":\"INCENTEA - PORTUGAL\"},\"image\":{\"@id\":\"https:\\\/\\\/incentea.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/incentea\\\/?locale=pt_PT\",\"https:\\\/\\\/www.instagram.com\\\/incenteatg\",\"https:\\\/\\\/pt.linkedin.com\\\/company\\\/incentea\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/incentea.com\\\/pt\\\/#\\\/schema\\\/person\\\/884fe8f51425a46e0eb1dec54cb42329\",\"name\":\"luisferreira\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e557c9a32ccfa2eb18ef4afe7bfc0589608a76e8160a217320931bcbe768d8b6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e557c9a32ccfa2eb18ef4afe7bfc0589608a76e8160a217320931bcbe768d8b6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e557c9a32ccfa2eb18ef4afe7bfc0589608a76e8160a217320931bcbe768d8b6?s=96&d=mm&r=g\",\"caption\":\"luisferreira\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"22\u00aa Conven\u00e7\u00e3o INCENTEA","description":"A INCENTEA voltou a provar, em 2026, que grandes empresas n\u00e3o se constroem apenas com estrat\u00e9gia, tecnologia ou resultados. Constroem-se com pessoas alinhadas pela mesma vis\u00e3o.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/incentea.com\/pt\/22a-convencao-incentea\/","og_locale":"pt_PT","og_type":"article","og_title":"22\u00aa Conven\u00e7\u00e3o INCENTEA","og_description":"A INCENTEA voltou a provar, em 2026, que grandes empresas n\u00e3o se constroem apenas com estrat\u00e9gia, tecnologia ou resultados. Constroem-se com pessoas alinhadas pela mesma vis\u00e3o.","og_url":"https:\/\/incentea.com\/pt\/22a-convencao-incentea\/","og_site_name":"INCENTEA Portugal","article_publisher":"https:\/\/www.facebook.com\/incentea\/?locale=pt_PT","article_published_time":"2026-04-21T15:55:37+00:00","article_modified_time":"2026-04-29T16:13:54+00:00","og_image":[{"width":1500,"height":937,"url":"https:\/\/incentea.com\/pt\/wp-content\/uploads\/sites\/3\/2026\/04\/INCENTEA_artigo-convencao.webp","type":"image\/webp"}],"author":"luisferreira","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"luisferreira","Tempo estimado de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/incentea.com\/pt\/22a-convencao-incentea\/#article","isPartOf":{"@id":"https:\/\/incentea.com\/pt\/22a-convencao-incentea\/"},"author":{"name":"luisferreira","@id":"https:\/\/incentea.com\/pt\/#\/schema\/person\/884fe8f51425a46e0eb1dec54cb42329"},"headline":"22\u00aa Conven\u00e7\u00e3o INCENTEA","datePublished":"2026-04-21T15:55:37+00:00","dateModified":"2026-04-29T16:13:54+00:00","mainEntityOfPage":{"@id":"https:\/\/incentea.com\/pt\/22a-convencao-incentea\/"},"wordCount":2885,"commentCount":0,"publisher":{"@id":"https:\/\/incentea.com\/pt\/#organization"},"image":{"@id":"https:\/\/incentea.com\/pt\/22a-convencao-incentea\/#primaryimage"},"thumbnailUrl":"https:\/\/incentea.com\/pt\/wp-content\/uploads\/sites\/3\/2026\/04\/INCENTEA_artigo-convencao.webp","articleSection":["Eventos","Noticias","Pessoas"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/incentea.com\/pt\/22a-convencao-incentea\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/incentea.com\/pt\/22a-convencao-incentea\/","url":"https:\/\/incentea.com\/pt\/22a-convencao-incentea\/","name":"22\u00aa Conven\u00e7\u00e3o INCENTEA","isPartOf":{"@id":"https:\/\/incentea.com\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/incentea.com\/pt\/22a-convencao-incentea\/#primaryimage"},"image":{"@id":"https:\/\/incentea.com\/pt\/22a-convencao-incentea\/#primaryimage"},"thumbnailUrl":"https:\/\/incentea.com\/pt\/wp-content\/uploads\/sites\/3\/2026\/04\/INCENTEA_artigo-convencao.webp","datePublished":"2026-04-21T15:55:37+00:00","dateModified":"2026-04-29T16:13:54+00:00","description":"A INCENTEA voltou a provar, em 2026, que grandes empresas n\u00e3o se constroem apenas com estrat\u00e9gia, tecnologia ou resultados. Constroem-se com pessoas alinhadas pela mesma vis\u00e3o.","breadcrumb":{"@id":"https:\/\/incentea.com\/pt\/22a-convencao-incentea\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/incentea.com\/pt\/22a-convencao-incentea\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/incentea.com\/pt\/22a-convencao-incentea\/#primaryimage","url":"https:\/\/incentea.com\/pt\/wp-content\/uploads\/sites\/3\/2026\/04\/INCENTEA_artigo-convencao.webp","contentUrl":"https:\/\/incentea.com\/pt\/wp-content\/uploads\/sites\/3\/2026\/04\/INCENTEA_artigo-convencao.webp","width":1500,"height":937},{"@type":"BreadcrumbList","@id":"https:\/\/incentea.com\/pt\/22a-convencao-incentea\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/incentea.com\/pt\/"},{"@type":"ListItem","position":2,"name":"22\u00aa Conven\u00e7\u00e3o INCENTEA"}]},{"@type":"WebSite","@id":"https:\/\/incentea.com\/pt\/#website","url":"https:\/\/incentea.com\/pt\/","name":"INCENTEA Portugal","description":"Website da INCENTEA em PORTUGAL","publisher":{"@id":"https:\/\/incentea.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/incentea.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/incentea.com\/pt\/#organization","name":"INCENTEA - PORTUGAL","url":"https:\/\/incentea.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/incentea.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/incentea.com\/pt\/wp-content\/uploads\/sites\/3\/2025\/09\/incentea_logo.svg","contentUrl":"https:\/\/incentea.com\/pt\/wp-content\/uploads\/sites\/3\/2025\/09\/incentea_logo.svg","width":251,"height":41,"caption":"INCENTEA - PORTUGAL"},"image":{"@id":"https:\/\/incentea.com\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/incentea\/?locale=pt_PT","https:\/\/www.instagram.com\/incenteatg","https:\/\/pt.linkedin.com\/company\/incentea"]},{"@type":"Person","@id":"https:\/\/incentea.com\/pt\/#\/schema\/person\/884fe8f51425a46e0eb1dec54cb42329","name":"luisferreira","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/e557c9a32ccfa2eb18ef4afe7bfc0589608a76e8160a217320931bcbe768d8b6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e557c9a32ccfa2eb18ef4afe7bfc0589608a76e8160a217320931bcbe768d8b6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e557c9a32ccfa2eb18ef4afe7bfc0589608a76e8160a217320931bcbe768d8b6?s=96&d=mm&r=g","caption":"luisferreira"}}]}},"_links":{"self":[{"href":"https:\/\/incentea.com\/pt\/wp-json\/wp\/v2\/posts\/4492","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/incentea.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/incentea.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/incentea.com\/pt\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/incentea.com\/pt\/wp-json\/wp\/v2\/comments?post=4492"}],"version-history":[{"count":4,"href":"https:\/\/incentea.com\/pt\/wp-json\/wp\/v2\/posts\/4492\/revisions"}],"predecessor-version":[{"id":4584,"href":"https:\/\/incentea.com\/pt\/wp-json\/wp\/v2\/posts\/4492\/revisions\/4584"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/incentea.com\/pt\/wp-json\/wp\/v2\/media\/4493"}],"wp:attachment":[{"href":"https:\/\/incentea.com\/pt\/wp-json\/wp\/v2\/media?parent=4492"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/incentea.com\/pt\/wp-json\/wp\/v2\/categories?post=4492"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/incentea.com\/pt\/wp-json\/wp\/v2\/tags?post=4492"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}