{"id":434,"date":"2025-10-01T08:39:06","date_gmt":"2025-10-01T08:39:06","guid":{"rendered":"https:\/\/incentea.yourcode-staging.com\/pt\/?post_type=casestudies&#038;p=434"},"modified":"2026-04-09T18:33:55","modified_gmt":"2026-04-09T18:33:55","slug":"a-j-maias-s-a","status":"publish","type":"casestudies","link":"https:\/\/incentea.com\/pt\/casestudies\/a-j-maias-s-a\/","title":{"rendered":"A.J. Maias, S.A."},"content":{"rendered":"[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;top&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;light&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; class=&#8221;heroSlider&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;column_reverse&#8221; column_direction_phone=&#8221;column_reverse&#8221; constrain_group_1=&#8221;yes&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner top_padding_desktop=&#8221;25%&#8221; left_padding_desktop=&#8221;12%&#8221; constrain_group_101=&#8221;yes&#8221; right_padding_desktop=&#8221;12%&#8221; top_padding_tablet=&#8221;10%&#8221; constrain_group_102=&#8221;yes&#8221; bottom_padding_tablet=&#8221;10%&#8221; left_padding_tablet=&#8221;7%&#8221; constrain_group_103=&#8221;yes&#8221; right_padding_tablet=&#8221;7%&#8221; top_padding_phone=&#8221;10%&#8221; constrain_group_104=&#8221;yes&#8221; bottom_padding_phone=&#8221;10%&#8221; left_padding_phone=&#8221;7%&#8221; constrain_group_105=&#8221;yes&#8221; right_padding_phone=&#8221;7%&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#0216CC&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;custom&#8221; bottom_left_border_radius=&#8221;40px&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; el_class=&#8221;m-br0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; gradient_type=&#8221;default&#8221;][vc_custom_heading text=&#8221;CONHE\u00c7A&#8221; font_container=&#8221;tag:h4|text_align:left|color:%235CF0B3&#8243; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<div class=\"product-category-wrapper\"><span class=\"categoria\">Sage<\/span><\/div>\n[\/vc_column_text][vc_custom_heading text=&#8221;A.J.Maias, S.A.&#8221; font_container=&#8221;tag:h1|text_align:left|color:%23FFFFFF&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]Implementa\u00e7\u00e3o do Sage ERP X3[\/vc_column_text][nectar_btn size=&#8221;medium&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Accent-Color&#8221; solid_text_color_override=&#8221;#FFFFFF&#8221; icon_family=&#8221;none&#8221; el_class=&#8221;button-blue-bullet&#8221; text=&#8221;Solu\u00e7\u00f5es&#8221; url=&#8221;\/pt\/solucoes&#8221;][\/vc_column_inner][vc_column_inner constrain_group_100=&#8221;yes&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;custom&#8221; bottom_right_border_radius=&#8221;40px&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; el_class=&#8221;m-br0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;1084&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; fit_to_container=&#8221;1&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;5%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; left_padding_desktop=&#8221;10%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;10%&#8221; left_padding_tablet=&#8221;0%&#8221; constrain_group_4=&#8221;yes&#8221; right_padding_tablet=&#8221;0%&#8221; left_padding_phone=&#8221;0%&#8221; constrain_group_6=&#8221;yes&#8221; right_padding_phone=&#8221;0%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h4><span style=\"color: #233dec;\">A.J.Maias, S.A.<\/span><\/h4>\n[\/vc_column_text][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h2>Implementa\u00e7\u00e3o do<br \/>\nSage ERP X3<\/h2>\n[\/vc_column_text][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]A A.J.Maias, S.A., terceira maior fabricante de bicicletas da Europa, implementou o Sage ERP X3 com o apoio da inCentea Wide para otimizar a rastreabilidade e gest\u00e3o da produ\u00e7\u00e3o, alinhando-se \u00e0s exig\u00eancias do setor e melhorando a efici\u00eancia operacional.[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;30&#8243; custom_height_phone=&#8221;10&#8243;][vc_video link=&#8221;https:\/\/www.youtube.com\/watch?v=e4f1NNe0PHU&#8221; el_width=&#8221;50&#8243; align=&#8221;center&#8221; css=&#8221;&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;top&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;5%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;5%&#8221; left_padding_desktop=&#8221;10%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;10%&#8221; left_padding_phone=&#8221;5%&#8221; constrain_group_6=&#8221;yes&#8221; right_padding_phone=&#8221;5%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column right_padding_desktop=&#8221;5%&#8221; right_padding_tablet=&#8221;0%&#8221; right_padding_phone=&#8221;0%&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<strong>Sobre a A.J.Maias, S.A.<\/strong><br \/>\n<strong>Setor:<\/strong>\u00a0Ind\u00fastria de bicicletas<br \/>\n<strong>Capacidade de\u00a0<\/strong><strong>Pintura:<\/strong>\u00a0500 quadros\/hora<br \/>\n<strong>Montagem:<\/strong>\u00a02.000 bicicletas\/dia<br \/>\n<strong>\u00c1rea coberta:<\/strong>\u00a0Mais de 10.000 m\u00b2<br \/>\n<strong>Colaboradores:<\/strong>\u00a0Aproximadamente 180<\/p>\n<p data-start=\"625\" data-end=\"1084\"><br data-start=\"827\" data-end=\"830\" \/>Com mais de 10.000 m\u00b2 de \u00e1rea industrial e uma equipa de cerca de 180 colaboradores, a empresa destaca-se pela flexibilidade, know-how t\u00e9cnico e pela capacidade de responder de forma r\u00e1pida \u00e0s exig\u00eancias de um mercado em constante evolu\u00e7\u00e3o.<\/p>\n<p data-start=\"1086\" data-end=\"1273\">A sua capacidade produtiva impressiona: 500 quadros pintados por hora e 2.000 bicicletas montadas por dia, refletindo uma opera\u00e7\u00e3o de elevada complexidade e exig\u00eancia tecnol\u00f3gica.<\/p>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<strong>O Desafio<\/strong><br \/>\nCom o crescimento da produ\u00e7\u00e3o e a diversidade das encomendas, a <strong data-start=\"1359\" data-end=\"1372\">A.J.Maias<\/strong> enfrentava desafios cr\u00edticos relacionados com a <strong data-start=\"1421\" data-end=\"1443\">gest\u00e3o operacional<\/strong>, a <strong data-start=\"1447\" data-end=\"1460\">log\u00edstica<\/strong> e a <strong data-start=\"1465\" data-end=\"1497\">rastreabilidade dos produtos<\/strong>.<br data-start=\"1498\" data-end=\"1501\" \/>O modelo de gest\u00e3o anterior j\u00e1 n\u00e3o acompanhava a escalabilidade necess\u00e1ria para garantir controlo total sobre o ciclo produtivo.[\/vc_column_text]<div class=\"nectar-fancy-ul\" data-list-icon=\"icon-salient-thin-line\" data-animation=\"false\" data-animation-delay=\"0\" data-color=\"accent-color\" data-spacing=\"default\" data-alignment=\"left\"> <strong>Log\u00edstica complexa: <\/strong>necessidade de gerir um fluxo intenso e diversificado de materiais e componentes.<\/p>\n<p><strong><br \/>\nRastreabilidade obrigat\u00f3ria:<\/strong> exig\u00eancia dos clientes de conhecer a origem e o percurso de cada componente da bicicleta.<\/p>\n<p><strong>Unifica\u00e7\u00e3o de sistemas:<\/strong> necessidade de integrar processos dispersos num sistema \u00fanico e centralizado.<\/p>\n<p><strong>Gest\u00e3o do ch\u00e3o de f\u00e1brica:<\/strong> aus\u00eancia de visibilidade em tempo real das ope <\/div>[\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;padding-4-percent&#8221; column_padding_position=&#8221;top&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][nectar_single_testimonial testimonial_style=&#8221;bold&#8221; color=&#8221;Accent-Color&#8221; quote=&#8221;A rela\u00e7\u00e3o com a equipa INCENTEA tem sido fant\u00e1stica, a comunica\u00e7\u00e3o \u00e9 muito f\u00e1cil e consegue-se fazer de forma simples e aberta, isso leva-nos a resultados mais r\u00e1pidos.&#8221; name=&#8221;Rui Tavares, Diretor Geral da A.J.Maias&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;1px&#8221; custom_height_phone=&#8221;5vh&#8221;][vc_column_text css_animation=&#8221;fadeIn&#8221; css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h4 data-start=\"3083\" data-end=\"3110\">Resultados e Benef\u00edcios<\/h4>\n<p data-start=\"3112\" data-end=\"3312\">A implementa\u00e7\u00e3o do <strong data-start=\"3131\" data-end=\"3146\">Sage ERP X3<\/strong> marcou um ponto de viragem na transforma\u00e7\u00e3o digital da A.J.Maias, traduzindo-se em ganhos expressivos de efici\u00eancia, rastreabilidade e agilidade operacional.<\/p>\n<h4 data-start=\"3314\" data-end=\"3352\">Otimiza\u00e7\u00e3o da Produ\u00e7\u00e3o e Controlo<\/h4>\n<ul data-start=\"3354\" data-end=\"3808\">\n<li data-start=\"3354\" data-end=\"3481\">\n<p data-start=\"3356\" data-end=\"3481\"><strong data-start=\"3356\" data-end=\"3385\">Rastreabilidade Completa:<\/strong> do momento da encomenda \u00e0 entrega final, cada bicicleta e componente \u00e9 totalmente rastre\u00e1vel.<\/p>\n<\/li>\n<li data-start=\"3482\" data-end=\"3608\">\n<p data-start=\"3484\" data-end=\"3608\"><strong data-start=\"3484\" data-end=\"3520\">Capta\u00e7\u00e3o de Dados em Tempo Real:<\/strong> monitoriza\u00e7\u00e3o do desempenho do ch\u00e3o de f\u00e1brica, m\u00e1quinas, tempos, consumos e equipas.<\/p>\n<\/li>\n<li data-start=\"3609\" data-end=\"3699\">\n<p data-start=\"3611\" data-end=\"3699\"><strong data-start=\"3611\" data-end=\"3644\">Gest\u00e3o de Stocks Inteligente:<\/strong> controlo rigoroso de invent\u00e1rio e redu\u00e7\u00e3o de perdas.<\/p>\n<\/li>\n<li data-start=\"3700\" data-end=\"3808\">\n<p data-start=\"3702\" data-end=\"3808\"><strong data-start=\"3702\" data-end=\"3728\">Comunica\u00e7\u00e3o Eficiente:<\/strong> integra\u00e7\u00e3o entre departamentos, eliminando redund\u00e2ncias e falhas de informa\u00e7\u00e3o.<\/p>\n<\/li>\n<\/ul>\n<h4 data-start=\"3810\" data-end=\"3841\">Agilidade e Escalabilidade<\/h4>\n<ul data-start=\"3843\" data-end=\"4151\">\n<li data-start=\"3843\" data-end=\"3941\">\n<p data-start=\"3845\" data-end=\"3941\"><strong data-start=\"3845\" data-end=\"3878\">Fluxos Produtivos Otimizados:<\/strong> processos mais r\u00e1pidos e adapt\u00e1veis \u00e0s varia\u00e7\u00f5es de mercado.<\/p>\n<\/li>\n<li data-start=\"3942\" data-end=\"4048\">\n<p data-start=\"3944\" data-end=\"4048\"><strong data-start=\"3944\" data-end=\"3977\">Maior Capacidade de Resposta:<\/strong> ERP preparado para acompanhar o crescimento e a evolu\u00e7\u00e3o da empresa.<\/p>\n<\/li>\n<li data-start=\"4049\" data-end=\"4151\">\n<p data-start=\"4051\" data-end=\"4151\"><strong data-start=\"4051\" data-end=\"4088\">Base s\u00f3lida para a Ind\u00fastria 4.0:<\/strong> integra\u00e7\u00e3o digital completa, preparada para futuras expans\u00f5es.<\/p>\n<\/li>\n<\/ul>\n[\/vc_column_text][divider line_type=&#8221;No Line&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; class=&#8221;solucoes&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h2>Descubra as nossas solu\u00e7\u00f5es<\/h2>\n[\/vc_column_text][nectar_post_grid post_type=&#8221;custom&#8221; cpt_name=&#8221;produto&#8221; order=&#8221;DESC&#8221; orderby=&#8221;date&#8221; pagination=&#8221;load-more&#8221; button_color=&#8221;accent-color&#8221; columns=&#8221;3&#8243; columns_tablet=&#8221;default&#8221; columns_phone=&#8221;default&#8221; grid_item_spacing=&#8221;25px&#8221; grid_item_height=&#8221;30vh&#8221; enable_sortable=&#8221;yes&#8221; cpt_all_filter=&#8221;yes&#8221; sortable_alignment=&#8221;left&#8221; sortable_color=&#8221;accent-color&#8221; 3_col_masonry_layout=&#8221;default&#8221; image_size=&#8221;medium&#8221; image_loading=&#8221;default&#8221; animation=&#8221;none&#8221; animation_stagger=&#8221;90&#8243; animation_easing=&#8221;default&#8221; heading_tag=&#8221;default&#8221; heading_tag_render=&#8221;default&#8221; font_size_min=&#8221;22px&#8221; font_size_max=&#8221;22px&#8221; category_position=&#8221;overlaid&#8221; display_excerpt=&#8221;yes&#8221; excerpt_display=&#8221;default&#8221; additional_meta_size=&#8221;default&#8221; custom_fields_location=&#8221;after_post_meta&#8221; grid_style=&#8221;content_under_image&#8221; card_design=&#8221;yes&#8221; card_bg_color=&#8221;#FFFFFF&#8221; content_under_image_text_align=&#8221;left&#8221; text_color=&#8221;dark&#8221; hover_effect=&#8221;animated_underline&#8221; border_radius=&#8221;20px&#8221; read_more_button=&#8221;yes&#8221; display_type=&#8221;grid&#8221; posts_per_page=&#8221;3&#8243; custom_font_size=&#8221;28px&#8221; custom_query_tax=&#8221;17&#8243;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; disable_element=&#8221;yes&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]I am text block. Click edit button to change this text. Lorem ipsum dolor sit amet, consectetur adipiscing elit. Ut elit tellus, luctus nec ullamcorper mattis, pulvinar dapibus leo.[\/vc_column_text][carousel script=&#8221;flickity&#8221; flickity_formatting=&#8221;default&#8221; desktop_cols_flickity=&#8221;2&#8243; desktop_small_cols_flickity=&#8221;1&#8243; tablet_cols_flickity=&#8221;1&#8243; phone_cols_flickity=&#8221;1&#8243; flickity_controls=&#8221;default&#8221; color=&#8221;accent-color&#8221; flickity_overflow=&#8221;hidden&#8221; flickity_wrap_around=&#8221;wrap&#8221; pagination_alignment_flickity=&#8221;default&#8221; flickity_spacing=&#8221;default&#8221; flickity_column_vertical_alignment=&#8221;default&#8221; column_padding=&#8221;0&#8243; flickity_element_spacing=&#8221;default&#8221; border_radius=&#8221;none&#8221;][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1775759847301-5&#8243; tab_id=&#8221;1775759847302-5&#8243; title=&#8221;Item&#8221;][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;top&#8221; column_margin=&#8221;none&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;column_reverse&#8221; column_direction_phone=&#8221;column_reverse&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; class=&#8221;m-br0&#8243;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;custom&#8221; top_left_border_radius=&#8221;40px&#8221; bottom_left_border_radius=&#8221;40px&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; el_class=&#8221;br-b-mobile&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;652&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221;][\/vc_column_inner][vc_column_inner top_padding_desktop=&#8221;10%&#8221; constrain_group_100=&#8221;yes&#8221; bottom_padding_desktop=&#8221;10%&#8221; left_padding_desktop=&#8221;10%&#8221; constrain_group_101=&#8221;yes&#8221; right_padding_desktop=&#8221;10%&#8221; top_padding_tablet=&#8221;10%&#8221; constrain_group_102=&#8221;yes&#8221; bottom_padding_tablet=&#8221;10%&#8221; left_padding_tablet=&#8221;10%&#8221; constrain_group_103=&#8221;yes&#8221; right_padding_tablet=&#8221;10%&#8221; top_padding_phone=&#8221;10%&#8221; constrain_group_104=&#8221;yes&#8221; bottom_padding_phone=&#8221;10%&#8221; left_padding_phone=&#8221;10%&#8221; constrain_group_105=&#8221;yes&#8221; right_padding_phone=&#8221;10%&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#19045A&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; font_color=&#8221;#FFFFFF&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;custom&#8221; top_right_border_radius=&#8221;40px&#8221; bottom_right_border_radius=&#8221;40px&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; el_class=&#8221;carousel-text br-t-mobile&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; gradient_type=&#8221;default&#8221;][vc_custom_heading text=&#8221;Case Study 1&#8243; font_container=&#8221;tag:h2|text_align:left|color:%235CF0B3&#8243; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]Lorem ipsum dolor sit amet consectetur. Eu vitae mi lectus eu laoreet. Mauris ipsum aliquam luctus.[\/vc_column_text][nectar_btn size=&#8221;medium&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Accent-Color&#8221; solid_text_color_override=&#8221;#FFFFFF&#8221; icon_family=&#8221;none&#8221; el_class=&#8221;button-blue-bullet&#8221; text=&#8221;Saber mais&#8221; url=&#8221;#&#8221;][\/vc_column_inner][\/vc_row_inner][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1775759847446-7&#8243; tab_id=&#8221;1775759847447-6&#8243; title=&#8221;Item&#8221;][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;top&#8221; column_margin=&#8221;none&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;column_reverse&#8221; column_direction_phone=&#8221;column_reverse&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; class=&#8221;m-br0&#8243;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;custom&#8221; top_left_border_radius=&#8221;40px&#8221; bottom_left_border_radius=&#8221;40px&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; el_class=&#8221;br-b-mobile&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;652&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221;][\/vc_column_inner][vc_column_inner top_padding_desktop=&#8221;10%&#8221; constrain_group_100=&#8221;yes&#8221; bottom_padding_desktop=&#8221;10%&#8221; left_padding_desktop=&#8221;10%&#8221; constrain_group_101=&#8221;yes&#8221; right_padding_desktop=&#8221;10%&#8221; top_padding_tablet=&#8221;10%&#8221; constrain_group_102=&#8221;yes&#8221; bottom_padding_tablet=&#8221;10%&#8221; left_padding_tablet=&#8221;10%&#8221; constrain_group_103=&#8221;yes&#8221; right_padding_tablet=&#8221;10%&#8221; top_padding_phone=&#8221;10%&#8221; constrain_group_104=&#8221;yes&#8221; bottom_padding_phone=&#8221;10%&#8221; left_padding_phone=&#8221;10%&#8221; constrain_group_105=&#8221;yes&#8221; right_padding_phone=&#8221;10%&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#19045A&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; font_color=&#8221;#FFFFFF&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;custom&#8221; top_right_border_radius=&#8221;40px&#8221; bottom_right_border_radius=&#8221;40px&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; el_class=&#8221;carousel-text br-t-mobile&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; gradient_type=&#8221;default&#8221;][vc_custom_heading text=&#8221;Case Study 1&#8243; font_container=&#8221;tag:h2|text_align:left|color:%235CF0B3&#8243; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]Lorem ipsum dolor sit amet consectetur. Eu vitae mi lectus eu laoreet. Mauris ipsum aliquam luctus.[\/vc_column_text][nectar_btn size=&#8221;medium&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Accent-Color&#8221; solid_text_color_override=&#8221;#FFFFFF&#8221; icon_family=&#8221;none&#8221; el_class=&#8221;button-blue-bullet&#8221; text=&#8221;Saber mais&#8221; url=&#8221;#&#8221;][\/vc_column_inner][\/vc_row_inner][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1775759847599-4&#8243; tab_id=&#8221;1775759847600-6&#8243; title=&#8221;Item&#8221;][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;top&#8221; column_margin=&#8221;none&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;column_reverse&#8221; column_direction_phone=&#8221;column_reverse&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; class=&#8221;m-br0&#8243;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;custom&#8221; top_left_border_radius=&#8221;40px&#8221; bottom_left_border_radius=&#8221;40px&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; el_class=&#8221;br-b-mobile&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;652&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221;][\/vc_column_inner][vc_column_inner top_padding_desktop=&#8221;10%&#8221; constrain_group_100=&#8221;yes&#8221; bottom_padding_desktop=&#8221;10%&#8221; left_padding_desktop=&#8221;10%&#8221; constrain_group_101=&#8221;yes&#8221; right_padding_desktop=&#8221;10%&#8221; top_padding_tablet=&#8221;10%&#8221; constrain_group_102=&#8221;yes&#8221; bottom_padding_tablet=&#8221;10%&#8221; left_padding_tablet=&#8221;10%&#8221; constrain_group_103=&#8221;yes&#8221; right_padding_tablet=&#8221;10%&#8221; top_padding_phone=&#8221;10%&#8221; constrain_group_104=&#8221;yes&#8221; bottom_padding_phone=&#8221;10%&#8221; left_padding_phone=&#8221;10%&#8221; constrain_group_105=&#8221;yes&#8221; right_padding_phone=&#8221;10%&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#19045A&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; font_color=&#8221;#FFFFFF&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;custom&#8221; top_right_border_radius=&#8221;40px&#8221; bottom_right_border_radius=&#8221;40px&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; el_class=&#8221;carousel-text br-t-mobile&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; gradient_type=&#8221;default&#8221;][vc_custom_heading text=&#8221;Case Study 1&#8243; font_container=&#8221;tag:h2|text_align:left|color:%235CF0B3&#8243; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]Lorem ipsum dolor sit amet consectetur. Eu vitae mi lectus eu laoreet. Mauris ipsum aliquam luctus.[\/vc_column_text][nectar_btn size=&#8221;medium&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Accent-Color&#8221; solid_text_color_override=&#8221;#FFFFFF&#8221; icon_family=&#8221;none&#8221; el_class=&#8221;button-blue-bullet&#8221; text=&#8221;Saber mais&#8221; url=&#8221;#&#8221;][\/vc_column_inner][\/vc_row_inner][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1775759847722-5&#8243; tab_id=&#8221;1775759847722-6&#8243; title=&#8221;Item&#8221;][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;top&#8221; column_margin=&#8221;none&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;column_reverse&#8221; column_direction_phone=&#8221;column_reverse&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; class=&#8221;m-br0&#8243;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;custom&#8221; top_left_border_radius=&#8221;40px&#8221; bottom_left_border_radius=&#8221;40px&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; el_class=&#8221;br-b-mobile&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;652&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221;][\/vc_column_inner][vc_column_inner top_padding_desktop=&#8221;10%&#8221; constrain_group_100=&#8221;yes&#8221; bottom_padding_desktop=&#8221;10%&#8221; left_padding_desktop=&#8221;10%&#8221; constrain_group_101=&#8221;yes&#8221; right_padding_desktop=&#8221;10%&#8221; top_padding_tablet=&#8221;10%&#8221; constrain_group_102=&#8221;yes&#8221; bottom_padding_tablet=&#8221;10%&#8221; left_padding_tablet=&#8221;10%&#8221; constrain_group_103=&#8221;yes&#8221; right_padding_tablet=&#8221;10%&#8221; top_padding_phone=&#8221;10%&#8221; constrain_group_104=&#8221;yes&#8221; bottom_padding_phone=&#8221;10%&#8221; left_padding_phone=&#8221;10%&#8221; constrain_group_105=&#8221;yes&#8221; right_padding_phone=&#8221;10%&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#19045A&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; font_color=&#8221;#FFFFFF&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;custom&#8221; top_right_border_radius=&#8221;40px&#8221; bottom_right_border_radius=&#8221;40px&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; el_class=&#8221;carousel-text br-t-mobile&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; gradient_type=&#8221;default&#8221;][vc_custom_heading text=&#8221;Case Study 1&#8243; font_container=&#8221;tag:h2|text_align:left|color:%235CF0B3&#8243; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]Lorem ipsum dolor sit amet consectetur. Eu vitae mi lectus eu laoreet. Mauris ipsum aliquam luctus.[\/vc_column_text][nectar_btn size=&#8221;medium&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Accent-Color&#8221; solid_text_color_override=&#8221;#FFFFFF&#8221; icon_family=&#8221;none&#8221; el_class=&#8221;button-blue-bullet&#8221; text=&#8221;Saber mais&#8221; url=&#8221;#&#8221;][\/vc_column_inner][\/vc_row_inner][\/item][\/carousel][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_margin_phone=&#8221;10%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_global_section id=&#8221;244&#8243;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_global_section id=&#8221;120&#8243;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>Implementa\u00e7\u00e3o do Sage ERP X3<\/p>\n","protected":false},"author":1,"featured_media":1084,"template":"","categories":[17],"tags":[],"class_list":{"0":"post-434","1":"casestudies","2":"type-casestudies","3":"status-publish","4":"has-post-thumbnail","6":"category-sage"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A.J. Maias, S.A. - INCENTEA Portugal<\/title>\n<meta name=\"description\" content=\"Descubra como a A.J.Maias, alcan\u00e7ou rastreabilidade total e efici\u00eancia operacional com o Sage X3 o ERP, implementado pela INCENTEA.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/incentea.com\/pt\/casestudies\/a-j-maias-s-a\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A.J. Maias, S.A. - INCENTEA Portugal\" \/>\n<meta property=\"og:description\" content=\"Descubra como a A.J.Maias, alcan\u00e7ou rastreabilidade total e efici\u00eancia operacional com o Sage X3 o ERP, implementado pela INCENTEA.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/incentea.com\/pt\/casestudies\/a-j-maias-s-a\/\" \/>\n<meta property=\"og:site_name\" content=\"INCENTEA Portugal\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/incentea\/?locale=pt_PT\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-09T18:33:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/incentea.com\/pt\/wp-content\/uploads\/sites\/3\/2025\/10\/bicicleta.png\" \/>\n\t<meta property=\"og:image:width\" content=\"902\" \/>\n\t<meta property=\"og:image:height\" content=\"638\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/incentea.com\\\/pt\\\/casestudies\\\/a-j-maias-s-a\\\/\",\"url\":\"https:\\\/\\\/incentea.com\\\/pt\\\/casestudies\\\/a-j-maias-s-a\\\/\",\"name\":\"A.J. Maias, S.A. - INCENTEA Portugal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/incentea.com\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/incentea.com\\\/pt\\\/casestudies\\\/a-j-maias-s-a\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/incentea.com\\\/pt\\\/casestudies\\\/a-j-maias-s-a\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/incentea.com\\\/pt\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/10\\\/bicicleta.png\",\"datePublished\":\"2025-10-01T08:39:06+00:00\",\"dateModified\":\"2026-04-09T18:33:55+00:00\",\"description\":\"Descubra como a A.J.Maias, alcan\u00e7ou rastreabilidade total e efici\u00eancia operacional com o Sage X3 o ERP, implementado pela INCENTEA.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/incentea.com\\\/pt\\\/casestudies\\\/a-j-maias-s-a\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/incentea.com\\\/pt\\\/casestudies\\\/a-j-maias-s-a\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/incentea.com\\\/pt\\\/casestudies\\\/a-j-maias-s-a\\\/#primaryimage\",\"url\":\"https:\\\/\\\/incentea.com\\\/pt\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/10\\\/bicicleta.png\",\"contentUrl\":\"https:\\\/\\\/incentea.com\\\/pt\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/10\\\/bicicleta.png\",\"width\":902,\"height\":638},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/incentea.com\\\/pt\\\/casestudies\\\/a-j-maias-s-a\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/incentea.com\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A.J. Maias, S.A.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/incentea.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/incentea.com\\\/pt\\\/\",\"name\":\"INCENTEA Portugal\",\"description\":\"Website da INCENTEA em PORTUGAL\",\"publisher\":{\"@id\":\"https:\\\/\\\/incentea.com\\\/pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/incentea.com\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/incentea.com\\\/pt\\\/#organization\",\"name\":\"INCENTEA - PORTUGAL\",\"url\":\"https:\\\/\\\/incentea.com\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/incentea.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/incentea.com\\\/pt\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/09\\\/incentea_logo.svg\",\"contentUrl\":\"https:\\\/\\\/incentea.com\\\/pt\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/09\\\/incentea_logo.svg\",\"width\":251,\"height\":41,\"caption\":\"INCENTEA - PORTUGAL\"},\"image\":{\"@id\":\"https:\\\/\\\/incentea.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/incentea\\\/?locale=pt_PT\",\"https:\\\/\\\/www.instagram.com\\\/incenteatg\",\"https:\\\/\\\/pt.linkedin.com\\\/company\\\/incentea\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A.J. Maias, S.A. - INCENTEA Portugal","description":"Descubra como a A.J.Maias, alcan\u00e7ou rastreabilidade total e efici\u00eancia operacional com o Sage X3 o ERP, implementado pela INCENTEA.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/incentea.com\/pt\/casestudies\/a-j-maias-s-a\/","og_locale":"pt_PT","og_type":"article","og_title":"A.J. Maias, S.A. - INCENTEA Portugal","og_description":"Descubra como a A.J.Maias, alcan\u00e7ou rastreabilidade total e efici\u00eancia operacional com o Sage X3 o ERP, implementado pela INCENTEA.","og_url":"https:\/\/incentea.com\/pt\/casestudies\/a-j-maias-s-a\/","og_site_name":"INCENTEA Portugal","article_publisher":"https:\/\/www.facebook.com\/incentea\/?locale=pt_PT","article_modified_time":"2026-04-09T18:33:55+00:00","og_image":[{"width":902,"height":638,"url":"https:\/\/incentea.com\/pt\/wp-content\/uploads\/sites\/3\/2025\/10\/bicicleta.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/incentea.com\/pt\/casestudies\/a-j-maias-s-a\/","url":"https:\/\/incentea.com\/pt\/casestudies\/a-j-maias-s-a\/","name":"A.J. Maias, S.A. - INCENTEA Portugal","isPartOf":{"@id":"https:\/\/incentea.com\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/incentea.com\/pt\/casestudies\/a-j-maias-s-a\/#primaryimage"},"image":{"@id":"https:\/\/incentea.com\/pt\/casestudies\/a-j-maias-s-a\/#primaryimage"},"thumbnailUrl":"https:\/\/incentea.com\/pt\/wp-content\/uploads\/sites\/3\/2025\/10\/bicicleta.png","datePublished":"2025-10-01T08:39:06+00:00","dateModified":"2026-04-09T18:33:55+00:00","description":"Descubra como a A.J.Maias, alcan\u00e7ou rastreabilidade total e efici\u00eancia operacional com o Sage X3 o ERP, implementado pela INCENTEA.","breadcrumb":{"@id":"https:\/\/incentea.com\/pt\/casestudies\/a-j-maias-s-a\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/incentea.com\/pt\/casestudies\/a-j-maias-s-a\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/incentea.com\/pt\/casestudies\/a-j-maias-s-a\/#primaryimage","url":"https:\/\/incentea.com\/pt\/wp-content\/uploads\/sites\/3\/2025\/10\/bicicleta.png","contentUrl":"https:\/\/incentea.com\/pt\/wp-content\/uploads\/sites\/3\/2025\/10\/bicicleta.png","width":902,"height":638},{"@type":"BreadcrumbList","@id":"https:\/\/incentea.com\/pt\/casestudies\/a-j-maias-s-a\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/incentea.com\/pt\/"},{"@type":"ListItem","position":2,"name":"A.J. Maias, S.A."}]},{"@type":"WebSite","@id":"https:\/\/incentea.com\/pt\/#website","url":"https:\/\/incentea.com\/pt\/","name":"INCENTEA Portugal","description":"Website da INCENTEA em PORTUGAL","publisher":{"@id":"https:\/\/incentea.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/incentea.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/incentea.com\/pt\/#organization","name":"INCENTEA - PORTUGAL","url":"https:\/\/incentea.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/incentea.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/incentea.com\/pt\/wp-content\/uploads\/sites\/3\/2025\/09\/incentea_logo.svg","contentUrl":"https:\/\/incentea.com\/pt\/wp-content\/uploads\/sites\/3\/2025\/09\/incentea_logo.svg","width":251,"height":41,"caption":"INCENTEA - PORTUGAL"},"image":{"@id":"https:\/\/incentea.com\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/incentea\/?locale=pt_PT","https:\/\/www.instagram.com\/incenteatg","https:\/\/pt.linkedin.com\/company\/incentea"]}]}},"_links":{"self":[{"href":"https:\/\/incentea.com\/pt\/wp-json\/wp\/v2\/casestudies\/434","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/incentea.com\/pt\/wp-json\/wp\/v2\/casestudies"}],"about":[{"href":"https:\/\/incentea.com\/pt\/wp-json\/wp\/v2\/types\/casestudies"}],"author":[{"embeddable":true,"href":"https:\/\/incentea.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/incentea.com\/pt\/wp-json\/wp\/v2\/casestudies\/434\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/incentea.com\/pt\/wp-json\/wp\/v2\/media\/1084"}],"wp:attachment":[{"href":"https:\/\/incentea.com\/pt\/wp-json\/wp\/v2\/media?parent=434"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/incentea.com\/pt\/wp-json\/wp\/v2\/categories?post=434"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/incentea.com\/pt\/wp-json\/wp\/v2\/tags?post=434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}