{"id":1553,"date":"2025-11-04T14:01:57","date_gmt":"2025-11-04T14:01:57","guid":{"rendered":"https:\/\/incentea.com\/cv\/?post_type=casestudies&#038;p=1553"},"modified":"2026-04-10T10:36:44","modified_gmt":"2026-04-10T10:36:44","slug":"fundacao-salesianos","status":"publish","type":"casestudies","link":"https:\/\/incentea.com\/cv\/en\/casestudies\/fundacao-salesianos\/","title":{"rendered":"Funda\u00e7\u00e3o Salesianos"},"content":{"rendered":"[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;top&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;light&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; class=&#8221;heroSlider&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;column_reverse&#8221; column_direction_phone=&#8221;column_reverse&#8221; constrain_group_1=&#8221;yes&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner constrain_group_100=&#8221;yes&#8221; left_padding_desktop=&#8221;12%&#8221; constrain_group_101=&#8221;yes&#8221; right_padding_desktop=&#8221;12%&#8221; top_padding_tablet=&#8221;10%&#8221; constrain_group_102=&#8221;yes&#8221; bottom_padding_tablet=&#8221;10%&#8221; left_padding_tablet=&#8221;7%&#8221; constrain_group_103=&#8221;yes&#8221; right_padding_tablet=&#8221;7%&#8221; top_padding_phone=&#8221;10%&#8221; constrain_group_104=&#8221;yes&#8221; bottom_padding_phone=&#8221;10%&#8221; left_padding_phone=&#8221;7%&#8221; constrain_group_105=&#8221;yes&#8221; right_padding_phone=&#8221;7%&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#0216CC&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;custom&#8221; bottom_left_border_radius=&#8221;40px&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; el_class=&#8221;m-br0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; gradient_type=&#8221;default&#8221;][vc_custom_heading text=&#8221;CONHE\u00c7A&#8221; font_container=&#8221;tag:h4|text_align:left|color:%235CF0B3&#8243; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<div class=\"product-category-wrapper\"><span class=\"categoria\">Sage<\/span><\/div>\n[\/vc_column_text][vc_custom_heading text=&#8221;Funda\u00e7\u00e3o Salesianos&#8221; font_container=&#8221;tag:h1|text_align:left|color:%23FFFFFF&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]Implementa\u00e7\u00e3o Cegid[\/vc_column_text][nectar_btn size=&#8221;medium&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Accent-Color&#8221; solid_text_color_override=&#8221;#FFFFFF&#8221; icon_family=&#8221;none&#8221; el_class=&#8221;button-blue-bullet&#8221; text=&#8221;Solu\u00e7\u00f5es&#8221; url=&#8221;\/cv\/solucoes&#8221;][\/vc_column_inner][vc_column_inner constrain_group_100=&#8221;yes&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;custom&#8221; bottom_right_border_radius=&#8221;40px&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; el_class=&#8221;m-br0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;1554&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; fit_to_container=&#8221;1&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;5%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; left_padding_desktop=&#8221;10%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;10%&#8221; left_padding_tablet=&#8221;0%&#8221; constrain_group_4=&#8221;yes&#8221; right_padding_tablet=&#8221;0%&#8221; left_padding_phone=&#8221;0%&#8221; constrain_group_6=&#8221;yes&#8221; right_padding_phone=&#8221;0%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/5&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;3\/5&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h4><span style=\"color: #233dec;\">Funda\u00e7\u00e3o Salesianos<\/span><\/h4>\n[\/vc_column_text][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h2>Implementa\u00e7\u00e3o do<br \/>\nCegid Primavera<\/h2>\n[\/vc_column_text][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<p data-start=\"677\" data-end=\"1071\">A Funda\u00e7\u00e3o Salesianos \u00e9 uma institui\u00e7\u00e3o com forte presen\u00e7a nacional, abrangendo 10 estabelecimentos de ensino e unidades de opera\u00e7\u00e3o distribu\u00eddos por diferentes regi\u00f5es do pa\u00eds.<br data-start=\"862\" data-end=\"865\" \/>A sua miss\u00e3o combina educa\u00e7\u00e3o, evangeliza\u00e7\u00e3o e forma\u00e7\u00e3o profissional, apoiada por \u00e1reas complementares como a edi\u00e7\u00e3o de conte\u00fados escolares e religiosos e a gest\u00e3o administrativa centralizada.<\/p>\n<p data-start=\"1073\" data-end=\"1266\">Com um ecossistema t\u00e3o diverso, a Funda\u00e7\u00e3o enfrentava o desafio de unificar opera\u00e7\u00f5es e sistemas tecnol\u00f3gicos para garantir uma gest\u00e3o eficaz, integrada e orientada para o futuro digital.<\/p>\n[\/vc_column_text][divider line_type=&#8221;No Line&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/5&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_video link=&#8221;https:\/\/www.youtube.com\/watch?v=GUeskNMtodE&#8221; el_width=&#8221;50&#8243; align=&#8221;center&#8221; css=&#8221;&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;5%&#8221; left_padding_desktop=&#8221;5%&#8221; left_padding_tablet=&#8221;0%&#8221; left_padding_phone=&#8221;0%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<p style=\"text-align: left;\"><strong data-start=\"417\" data-end=\"429\">Cliente:<\/strong> Funda\u00e7\u00e3o Salesianos<br data-start=\"449\" data-end=\"452\" \/><strong data-start=\"452\" data-end=\"462\">Setor:<\/strong> Educa\u00e7\u00e3o, Forma\u00e7\u00e3o e Publica\u00e7\u00f5es<br data-start=\"495\" data-end=\"498\" \/><strong data-start=\"498\" data-end=\"511\">Solu\u00e7\u00f5es:<\/strong> Primavera | Cegid | Integra\u00e7\u00e3o Multiplataforma | Loja Online Salesianos Editora<br \/>\n<strong>Localiza\u00e7\u00e3o:<\/strong> Portugal<\/p>\n[\/vc_column_text][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h3 data-start=\"1043\" data-end=\"1058\">O Desafio<\/h3>\n<p data-start=\"1059\" data-end=\"1159\">Com a transforma\u00e7\u00e3o da institui\u00e7\u00e3o numa funda\u00e7\u00e3o, surgiu a necessidade de criar um modelo de <strong data-start=\"1383\" data-end=\"1413\">gest\u00e3o \u00fanica e transversal<\/strong> a todos os estabelecimentos.<br data-start=\"1442\" data-end=\"1445\" \/>At\u00e9 ent\u00e3o, cada unidade funcionava de forma independente, com sistemas pr\u00f3prios e fluxos de informa\u00e7\u00e3o distintos \u2014 o que dificultava a consolida\u00e7\u00e3o de dados e a uniformiza\u00e7\u00e3o de processos.<\/p>\n<p data-start=\"1637\" data-end=\"1690\">Entre os principais desafios identificados estavam:<\/p>\n<ol data-start=\"1692\" data-end=\"2275\">\n<li data-start=\"1692\" data-end=\"1806\">\n<p data-start=\"1695\" data-end=\"1806\"><strong data-start=\"1695\" data-end=\"1727\">Descentraliza\u00e7\u00e3o de sistemas<\/strong> \u2013 cada estabelecimento utilizava ferramentas e m\u00e9todos diferentes de gest\u00e3o.<\/p>\n<\/li>\n<li data-start=\"1807\" data-end=\"1944\">\n<p data-start=\"1810\" data-end=\"1944\"><strong data-start=\"1810\" data-end=\"1853\">Falta de integra\u00e7\u00e3o entre departamentos<\/strong> \u2013 vendas, fatura\u00e7\u00e3o e expedi\u00e7\u00e3o operavam de forma redundante, criando inefici\u00eancias.<\/p>\n<\/li>\n<li data-start=\"1945\" data-end=\"2084\">\n<p data-start=\"1948\" data-end=\"2084\"><strong data-start=\"1948\" data-end=\"1975\">Gest\u00e3o central complexa<\/strong> \u2013 a transi\u00e7\u00e3o para uma funda\u00e7\u00e3o exigia reporting consolidado e visibilidade global sobre as opera\u00e7\u00f5es.<\/p>\n<\/li>\n<li data-start=\"2085\" data-end=\"2275\">\n<p data-start=\"2088\" data-end=\"2275\"><strong data-start=\"2088\" data-end=\"2125\">Otimiza\u00e7\u00e3o da experi\u00eancia digital<\/strong> \u2013 a loja online da <em data-start=\"2145\" data-end=\"2165\">Salesianos Editora<\/em> precisava de maior fluidez entre pedidos, fatura\u00e7\u00e3o e expedi\u00e7\u00e3o, para melhorar a experi\u00eancia de compra.<\/p>\n<\/li>\n<\/ol>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h3 data-start=\"1646\" data-end=\"1685\">A Solu\u00e7\u00e3o: Integra\u00e7\u00e3o de Sistemas e Digitaliza\u00e7\u00e3o<\/h3>\n<p data-start=\"2354\" data-end=\"2562\">A parceria entre a Funda\u00e7\u00e3o Salesianos e a INCENTEA iniciou-se h\u00e1 mais de 20 anos, com a implementa\u00e7\u00e3o de solu\u00e7\u00f5es Primavera e Cegid, que viriam a tornar-se pilares da gest\u00e3o da institui\u00e7\u00e3o.<\/p>\n<p data-start=\"2564\" data-end=\"2899\">A mais recente fase de colabora\u00e7\u00e3o centrou-se na digitaliza\u00e7\u00e3o e integra\u00e7\u00e3o de sistemas cr\u00edticos, com destaque para a moderniza\u00e7\u00e3o da loja online da Salesianos Editora.<br data-start=\"2740\" data-end=\"2743\" \/>Esta integra\u00e7\u00e3o, desenvolvida pela inCentea, permitiu criar autonomia entre departamentos, eliminando redund\u00e2ncias e acelerando a resposta ao cliente.<\/p>\n<h4 data-start=\"2901\" data-end=\"2940\">Principais destaques da solu\u00e7\u00e3o:<\/h4>\n<ul data-start=\"2941\" data-end=\"3361\">\n<li data-start=\"2941\" data-end=\"3073\">\n<p data-start=\"2943\" data-end=\"3073\"><strong data-start=\"2943\" data-end=\"2997\">Integra\u00e7\u00e3o entre sistemas ERP e plataformas online<\/strong>, garantindo a comunica\u00e7\u00e3o autom\u00e1tica entre vendas, fatura\u00e7\u00e3o e expedi\u00e7\u00e3o.<\/p>\n<\/li>\n<li data-start=\"3074\" data-end=\"3154\">\n<p data-start=\"3076\" data-end=\"3154\"><strong data-start=\"3076\" data-end=\"3118\">Automatiza\u00e7\u00e3o de processos repetitivos<\/strong>, reduzindo tempo e erros humanos.<\/p>\n<\/li>\n<li data-start=\"3155\" data-end=\"3248\">\n<p data-start=\"3157\" data-end=\"3248\"><strong data-start=\"3157\" data-end=\"3192\">Fluxos de informa\u00e7\u00e3o unificados<\/strong>, suportados por uma infraestrutura digital escal\u00e1vel.<\/p>\n<\/li>\n<li data-start=\"3249\" data-end=\"3361\">\n<p data-start=\"3251\" data-end=\"3361\"><strong data-start=\"3251\" data-end=\"3290\">Acompanhamento tecnol\u00f3gico cont\u00ednuo<\/strong>, com a inCentea a adaptar solu\u00e7\u00f5es \u00e0s novas necessidades do cliente.<\/p>\n<\/li>\n<\/ul>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;5%&#8221; left_padding_desktop=&#8221;5%&#8221; left_padding_tablet=&#8221;0%&#8221; left_padding_phone=&#8221;0%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_single_testimonial testimonial_style=&#8221;bold&#8221; color=&#8221;Default&#8221; quote=&#8221;A implementa\u00e7\u00e3o da nova loja online permitiu-nos trabalhar de forma aut\u00f3noma entre os departamentos de vendas, fatura\u00e7\u00e3o e expedi\u00e7\u00e3o, eliminando redund\u00e2ncias e aumentando a efici\u00eancia.&#8221; name=&#8221;\u2014 Equipa de Gest\u00e3o, Salesianos Editora&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;5%&#8221; left_padding_desktop=&#8221;5%&#8221; left_padding_tablet=&#8221;0%&#8221; left_padding_phone=&#8221;0%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<p style=\"text-align: center;\" data-start=\"4541\" data-end=\"4556\">A colabora\u00e7\u00e3o entre os Salesianos e a inCentea \u00e9 um exemplo de como a integra\u00e7\u00e3o tecnol\u00f3gica e a vis\u00e3o partilhada podem transformar a gest\u00e3o de uma institui\u00e7\u00e3o complexa e multifacetada.<br data-start=\"4755\" data-end=\"4758\" \/>Com solu\u00e7\u00f5es que ligam sistemas, pessoas e processos, a Funda\u00e7\u00e3o Salesianos refor\u00e7a a sua efici\u00eancia organizacional, mant\u00e9m-se fiel \u00e0 sua miss\u00e3o educativa e posiciona-se na vanguarda da transforma\u00e7\u00e3o digital no setor da educa\u00e7\u00e3o.<\/p>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; class=&#8221;solucoes&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_post_grid post_type=&#8221;custom&#8221; cpt_name=&#8221;produto&#8221; order=&#8221;DESC&#8221; orderby=&#8221;date&#8221; pagination=&#8221;load-more&#8221; button_color=&#8221;accent-color&#8221; columns=&#8221;3&#8243; columns_tablet=&#8221;default&#8221; columns_phone=&#8221;default&#8221; grid_item_spacing=&#8221;25px&#8221; grid_item_height=&#8221;30vh&#8221; enable_sortable=&#8221;yes&#8221; cpt_all_filter=&#8221;yes&#8221; sortable_alignment=&#8221;left&#8221; sortable_color=&#8221;accent-color&#8221; 3_col_masonry_layout=&#8221;default&#8221; image_size=&#8221;medium&#8221; image_loading=&#8221;default&#8221; animation=&#8221;none&#8221; animation_stagger=&#8221;90&#8243; animation_easing=&#8221;default&#8221; heading_tag=&#8221;default&#8221; heading_tag_render=&#8221;default&#8221; font_size_min=&#8221;22px&#8221; font_size_max=&#8221;22px&#8221; category_position=&#8221;overlaid&#8221; display_excerpt=&#8221;yes&#8221; excerpt_display=&#8221;default&#8221; additional_meta_size=&#8221;default&#8221; custom_fields_location=&#8221;after_post_meta&#8221; grid_style=&#8221;content_under_image&#8221; card_design=&#8221;yes&#8221; card_bg_color=&#8221;#FFFFFF&#8221; content_under_image_text_align=&#8221;left&#8221; text_color=&#8221;dark&#8221; hover_effect=&#8221;animated_underline&#8221; border_radius=&#8221;20px&#8221; read_more_button=&#8221;yes&#8221; display_type=&#8221;grid&#8221; posts_per_page=&#8221;3&#8243; custom_font_size=&#8221;28px&#8221; custom_query_tax=&#8221;27&#8243;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; disable_element=&#8221;yes&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][carousel script=&#8221;flickity&#8221; flickity_formatting=&#8221;default&#8221; desktop_cols_flickity=&#8221;2&#8243; desktop_small_cols_flickity=&#8221;1&#8243; tablet_cols_flickity=&#8221;1&#8243; phone_cols_flickity=&#8221;1&#8243; flickity_controls=&#8221;default&#8221; color=&#8221;accent-color&#8221; flickity_overflow=&#8221;hidden&#8221; flickity_wrap_around=&#8221;wrap&#8221; pagination_alignment_flickity=&#8221;default&#8221; flickity_spacing=&#8221;default&#8221; flickity_column_vertical_alignment=&#8221;default&#8221; column_padding=&#8221;0&#8243; flickity_element_spacing=&#8221;default&#8221; border_radius=&#8221;none&#8221;][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1775817618394-10&#8243; tab_id=&#8221;1775817618395-0&#8243; title=&#8221;Item&#8221;][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;top&#8221; column_margin=&#8221;none&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;column_reverse&#8221; column_direction_phone=&#8221;column_reverse&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; class=&#8221;m-br0&#8243;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;custom&#8221; top_left_border_radius=&#8221;40px&#8221; bottom_left_border_radius=&#8221;40px&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; el_class=&#8221;br-b-mobile&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;652&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221;][\/vc_column_inner][vc_column_inner top_padding_desktop=&#8221;10%&#8221; constrain_group_100=&#8221;yes&#8221; bottom_padding_desktop=&#8221;10%&#8221; left_padding_desktop=&#8221;10%&#8221; constrain_group_101=&#8221;yes&#8221; right_padding_desktop=&#8221;10%&#8221; top_padding_tablet=&#8221;10%&#8221; constrain_group_102=&#8221;yes&#8221; bottom_padding_tablet=&#8221;10%&#8221; left_padding_tablet=&#8221;10%&#8221; constrain_group_103=&#8221;yes&#8221; right_padding_tablet=&#8221;10%&#8221; top_padding_phone=&#8221;10%&#8221; constrain_group_104=&#8221;yes&#8221; bottom_padding_phone=&#8221;10%&#8221; left_padding_phone=&#8221;10%&#8221; constrain_group_105=&#8221;yes&#8221; right_padding_phone=&#8221;10%&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#19045A&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; font_color=&#8221;#FFFFFF&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;custom&#8221; top_right_border_radius=&#8221;40px&#8221; bottom_right_border_radius=&#8221;40px&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; el_class=&#8221;carousel-text br-t-mobile&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; gradient_type=&#8221;default&#8221;][vc_custom_heading text=&#8221;Case Study 1&#8243; font_container=&#8221;tag:h2|text_align:left|color:%235CF0B3&#8243; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]Lorem ipsum dolor sit amet consectetur. Eu vitae mi lectus eu laoreet. Mauris ipsum aliquam luctus.[\/vc_column_text][nectar_btn size=&#8221;medium&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Accent-Color&#8221; solid_text_color_override=&#8221;#FFFFFF&#8221; icon_family=&#8221;none&#8221; el_class=&#8221;button-blue-bullet&#8221; text=&#8221;Saber mais&#8221; url=&#8221;#&#8221;][\/vc_column_inner][\/vc_row_inner][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1775817618664-10&#8243; tab_id=&#8221;1775817618665-3&#8243; title=&#8221;Item&#8221;][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;top&#8221; column_margin=&#8221;none&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;column_reverse&#8221; column_direction_phone=&#8221;column_reverse&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; class=&#8221;m-br0&#8243;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;custom&#8221; top_left_border_radius=&#8221;40px&#8221; bottom_left_border_radius=&#8221;40px&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; el_class=&#8221;br-b-mobile&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;652&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221;][\/vc_column_inner][vc_column_inner top_padding_desktop=&#8221;10%&#8221; constrain_group_100=&#8221;yes&#8221; bottom_padding_desktop=&#8221;10%&#8221; left_padding_desktop=&#8221;10%&#8221; constrain_group_101=&#8221;yes&#8221; right_padding_desktop=&#8221;10%&#8221; top_padding_tablet=&#8221;10%&#8221; constrain_group_102=&#8221;yes&#8221; bottom_padding_tablet=&#8221;10%&#8221; left_padding_tablet=&#8221;10%&#8221; constrain_group_103=&#8221;yes&#8221; right_padding_tablet=&#8221;10%&#8221; top_padding_phone=&#8221;10%&#8221; constrain_group_104=&#8221;yes&#8221; bottom_padding_phone=&#8221;10%&#8221; left_padding_phone=&#8221;10%&#8221; constrain_group_105=&#8221;yes&#8221; right_padding_phone=&#8221;10%&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#19045A&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; font_color=&#8221;#FFFFFF&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;custom&#8221; top_right_border_radius=&#8221;40px&#8221; bottom_right_border_radius=&#8221;40px&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; el_class=&#8221;carousel-text br-t-mobile&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; gradient_type=&#8221;default&#8221;][vc_custom_heading text=&#8221;Case Study 1&#8243; font_container=&#8221;tag:h2|text_align:left|color:%235CF0B3&#8243; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]Lorem ipsum dolor sit amet consectetur. Eu vitae mi lectus eu laoreet. Mauris ipsum aliquam luctus.[\/vc_column_text][nectar_btn size=&#8221;medium&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Accent-Color&#8221; solid_text_color_override=&#8221;#FFFFFF&#8221; icon_family=&#8221;none&#8221; el_class=&#8221;button-blue-bullet&#8221; text=&#8221;Saber mais&#8221; url=&#8221;#&#8221;][\/vc_column_inner][\/vc_row_inner][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1775817618866-0&#8243; tab_id=&#8221;1775817618867-1&#8243; title=&#8221;Item&#8221;][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;top&#8221; column_margin=&#8221;none&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;column_reverse&#8221; column_direction_phone=&#8221;column_reverse&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; class=&#8221;m-br0&#8243;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;custom&#8221; top_left_border_radius=&#8221;40px&#8221; bottom_left_border_radius=&#8221;40px&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; el_class=&#8221;br-b-mobile&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;652&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221;][\/vc_column_inner][vc_column_inner top_padding_desktop=&#8221;10%&#8221; constrain_group_100=&#8221;yes&#8221; bottom_padding_desktop=&#8221;10%&#8221; left_padding_desktop=&#8221;10%&#8221; constrain_group_101=&#8221;yes&#8221; right_padding_desktop=&#8221;10%&#8221; top_padding_tablet=&#8221;10%&#8221; constrain_group_102=&#8221;yes&#8221; bottom_padding_tablet=&#8221;10%&#8221; left_padding_tablet=&#8221;10%&#8221; constrain_group_103=&#8221;yes&#8221; right_padding_tablet=&#8221;10%&#8221; top_padding_phone=&#8221;10%&#8221; constrain_group_104=&#8221;yes&#8221; bottom_padding_phone=&#8221;10%&#8221; left_padding_phone=&#8221;10%&#8221; constrain_group_105=&#8221;yes&#8221; right_padding_phone=&#8221;10%&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#19045A&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; font_color=&#8221;#FFFFFF&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;custom&#8221; top_right_border_radius=&#8221;40px&#8221; bottom_right_border_radius=&#8221;40px&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; el_class=&#8221;carousel-text br-t-mobile&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; gradient_type=&#8221;default&#8221;][vc_custom_heading text=&#8221;Case Study 1&#8243; font_container=&#8221;tag:h2|text_align:left|color:%235CF0B3&#8243; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]Lorem ipsum dolor sit amet consectetur. Eu vitae mi lectus eu laoreet. Mauris ipsum aliquam luctus.[\/vc_column_text][nectar_btn size=&#8221;medium&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Accent-Color&#8221; solid_text_color_override=&#8221;#FFFFFF&#8221; icon_family=&#8221;none&#8221; el_class=&#8221;button-blue-bullet&#8221; text=&#8221;Saber mais&#8221; url=&#8221;#&#8221;][\/vc_column_inner][\/vc_row_inner][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1775817619059-10&#8243; tab_id=&#8221;1775817619059-4&#8243; title=&#8221;Item&#8221;][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;top&#8221; column_margin=&#8221;none&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;column_reverse&#8221; column_direction_phone=&#8221;column_reverse&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; class=&#8221;m-br0&#8243;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;custom&#8221; top_left_border_radius=&#8221;40px&#8221; bottom_left_border_radius=&#8221;40px&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; el_class=&#8221;br-b-mobile&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;652&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221;][\/vc_column_inner][vc_column_inner top_padding_desktop=&#8221;10%&#8221; constrain_group_100=&#8221;yes&#8221; bottom_padding_desktop=&#8221;10%&#8221; left_padding_desktop=&#8221;10%&#8221; constrain_group_101=&#8221;yes&#8221; right_padding_desktop=&#8221;10%&#8221; top_padding_tablet=&#8221;10%&#8221; constrain_group_102=&#8221;yes&#8221; bottom_padding_tablet=&#8221;10%&#8221; left_padding_tablet=&#8221;10%&#8221; constrain_group_103=&#8221;yes&#8221; right_padding_tablet=&#8221;10%&#8221; top_padding_phone=&#8221;10%&#8221; constrain_group_104=&#8221;yes&#8221; bottom_padding_phone=&#8221;10%&#8221; left_padding_phone=&#8221;10%&#8221; constrain_group_105=&#8221;yes&#8221; right_padding_phone=&#8221;10%&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#19045A&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; font_color=&#8221;#FFFFFF&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;custom&#8221; top_right_border_radius=&#8221;40px&#8221; bottom_right_border_radius=&#8221;40px&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; el_class=&#8221;carousel-text br-t-mobile&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; gradient_type=&#8221;default&#8221;][vc_custom_heading text=&#8221;Case Study 1&#8243; font_container=&#8221;tag:h2|text_align:left|color:%235CF0B3&#8243; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]Lorem ipsum dolor sit amet consectetur. Eu vitae mi lectus eu laoreet. Mauris ipsum aliquam luctus.[\/vc_column_text][nectar_btn size=&#8221;medium&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Accent-Color&#8221; solid_text_color_override=&#8221;#FFFFFF&#8221; icon_family=&#8221;none&#8221; el_class=&#8221;button-blue-bullet&#8221; text=&#8221;Saber mais&#8221; url=&#8221;#&#8221;][\/vc_column_inner][\/vc_row_inner][\/item][\/carousel][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_global_section id=&#8221;244&#8243;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_global_section id=&#8221;120&#8243;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;top&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;light&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; class=&#8221;heroSlider&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221;&#8230;<\/p>\n","protected":false},"author":3,"featured_media":1554,"template":"","categories":[],"tags":[],"class_list":["post-1553","casestudies","type-casestudies","status-publish","has-post-thumbnail"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Funda\u00e7\u00e3o Salesianos - INCENTEA Cabo Verde<\/title>\n<meta name=\"description\" content=\"Como a Sociedade Transformadora de Alum\u00ednios (S.T.A.) modernizou o seu ERP com o Sage X3 e a INCENTEA, alcan\u00e7ando maior efici\u00eancia e flexibilidade na produ\u00e7\u00e3o de sistemas em alum\u00ednio.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/incentea.com\/cv\/casestudies\/fundacao-salesianos\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Funda\u00e7\u00e3o Salesianos - INCENTEA Cabo Verde\" \/>\n<meta property=\"og:description\" content=\"Como a Sociedade Transformadora de Alum\u00ednios (S.T.A.) modernizou o seu ERP com o Sage X3 e a INCENTEA, alcan\u00e7ando maior efici\u00eancia e flexibilidade na produ\u00e7\u00e3o de sistemas em alum\u00ednio.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/incentea.com\/cv\/casestudies\/fundacao-salesianos\/\" \/>\n<meta property=\"og:site_name\" content=\"INCENTEA Cabo Verde\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-10T10:36:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/incentea.com\/cv\/wp-content\/uploads\/sites\/6\/2025\/11\/fundacao_comunicado-jpg-webp.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/incentea.com\\\/cv\\\/casestudies\\\/fundacao-salesianos\\\/\",\"url\":\"https:\\\/\\\/incentea.com\\\/cv\\\/casestudies\\\/fundacao-salesianos\\\/\",\"name\":\"Funda\u00e7\u00e3o Salesianos - INCENTEA Cabo Verde\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/incentea.com\\\/cv\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/incentea.com\\\/cv\\\/casestudies\\\/fundacao-salesianos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/incentea.com\\\/cv\\\/casestudies\\\/fundacao-salesianos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/incentea.com\\\/cv\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2025\\\/11\\\/fundacao_comunicado-jpg-webp.webp\",\"datePublished\":\"2025-11-04T14:01:57+00:00\",\"dateModified\":\"2026-04-10T10:36:44+00:00\",\"description\":\"Como a Sociedade Transformadora de Alum\u00ednios (S.T.A.) modernizou o seu ERP com o Sage X3 e a INCENTEA, alcan\u00e7ando maior efici\u00eancia e flexibilidade na produ\u00e7\u00e3o de sistemas em alum\u00ednio.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/incentea.com\\\/cv\\\/casestudies\\\/fundacao-salesianos\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/incentea.com\\\/cv\\\/casestudies\\\/fundacao-salesianos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/incentea.com\\\/cv\\\/casestudies\\\/fundacao-salesianos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/incentea.com\\\/cv\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2025\\\/11\\\/fundacao_comunicado-jpg-webp.webp\",\"contentUrl\":\"https:\\\/\\\/incentea.com\\\/cv\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2025\\\/11\\\/fundacao_comunicado-jpg-webp.webp\",\"width\":1200,\"height\":628},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/incentea.com\\\/cv\\\/casestudies\\\/fundacao-salesianos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/incentea.com\\\/cv\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Funda\u00e7\u00e3o Salesianos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/incentea.com\\\/cv\\\/#website\",\"url\":\"https:\\\/\\\/incentea.com\\\/cv\\\/\",\"name\":\"INCENTEA Cabo Verde\",\"description\":\"Website da INCENTEA em CABO VERDE\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/incentea.com\\\/cv\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Funda\u00e7\u00e3o Salesianos - INCENTEA Cabo Verde","description":"Como a Sociedade Transformadora de Alum\u00ednios (S.T.A.) modernizou o seu ERP com o Sage X3 e a INCENTEA, alcan\u00e7ando maior efici\u00eancia e flexibilidade na produ\u00e7\u00e3o de sistemas em alum\u00ednio.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/incentea.com\/cv\/casestudies\/fundacao-salesianos\/","og_locale":"en_US","og_type":"article","og_title":"Funda\u00e7\u00e3o Salesianos - INCENTEA Cabo Verde","og_description":"Como a Sociedade Transformadora de Alum\u00ednios (S.T.A.) modernizou o seu ERP com o Sage X3 e a INCENTEA, alcan\u00e7ando maior efici\u00eancia e flexibilidade na produ\u00e7\u00e3o de sistemas em alum\u00ednio.","og_url":"https:\/\/incentea.com\/cv\/casestudies\/fundacao-salesianos\/","og_site_name":"INCENTEA Cabo Verde","article_modified_time":"2026-04-10T10:36:44+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/incentea.com\/cv\/wp-content\/uploads\/sites\/6\/2025\/11\/fundacao_comunicado-jpg-webp.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/incentea.com\/cv\/casestudies\/fundacao-salesianos\/","url":"https:\/\/incentea.com\/cv\/casestudies\/fundacao-salesianos\/","name":"Funda\u00e7\u00e3o Salesianos - INCENTEA Cabo Verde","isPartOf":{"@id":"https:\/\/incentea.com\/cv\/#website"},"primaryImageOfPage":{"@id":"https:\/\/incentea.com\/cv\/casestudies\/fundacao-salesianos\/#primaryimage"},"image":{"@id":"https:\/\/incentea.com\/cv\/casestudies\/fundacao-salesianos\/#primaryimage"},"thumbnailUrl":"https:\/\/incentea.com\/cv\/wp-content\/uploads\/sites\/6\/2025\/11\/fundacao_comunicado-jpg-webp.webp","datePublished":"2025-11-04T14:01:57+00:00","dateModified":"2026-04-10T10:36:44+00:00","description":"Como a Sociedade Transformadora de Alum\u00ednios (S.T.A.) modernizou o seu ERP com o Sage X3 e a INCENTEA, alcan\u00e7ando maior efici\u00eancia e flexibilidade na produ\u00e7\u00e3o de sistemas em alum\u00ednio.","breadcrumb":{"@id":"https:\/\/incentea.com\/cv\/casestudies\/fundacao-salesianos\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/incentea.com\/cv\/casestudies\/fundacao-salesianos\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/incentea.com\/cv\/casestudies\/fundacao-salesianos\/#primaryimage","url":"https:\/\/incentea.com\/cv\/wp-content\/uploads\/sites\/6\/2025\/11\/fundacao_comunicado-jpg-webp.webp","contentUrl":"https:\/\/incentea.com\/cv\/wp-content\/uploads\/sites\/6\/2025\/11\/fundacao_comunicado-jpg-webp.webp","width":1200,"height":628},{"@type":"BreadcrumbList","@id":"https:\/\/incentea.com\/cv\/casestudies\/fundacao-salesianos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/incentea.com\/cv\/"},{"@type":"ListItem","position":2,"name":"Funda\u00e7\u00e3o Salesianos"}]},{"@type":"WebSite","@id":"https:\/\/incentea.com\/cv\/#website","url":"https:\/\/incentea.com\/cv\/","name":"INCENTEA Cabo Verde","description":"Website da INCENTEA em CABO VERDE","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/incentea.com\/cv\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/incentea.com\/cv\/en\/wp-json\/wp\/v2\/casestudies\/1553","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/incentea.com\/cv\/en\/wp-json\/wp\/v2\/casestudies"}],"about":[{"href":"https:\/\/incentea.com\/cv\/en\/wp-json\/wp\/v2\/types\/casestudies"}],"author":[{"embeddable":true,"href":"https:\/\/incentea.com\/cv\/en\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":6,"href":"https:\/\/incentea.com\/cv\/en\/wp-json\/wp\/v2\/casestudies\/1553\/revisions"}],"predecessor-version":[{"id":2793,"href":"https:\/\/incentea.com\/cv\/en\/wp-json\/wp\/v2\/casestudies\/1553\/revisions\/2793"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/incentea.com\/cv\/en\/wp-json\/wp\/v2\/media\/1554"}],"wp:attachment":[{"href":"https:\/\/incentea.com\/cv\/en\/wp-json\/wp\/v2\/media?parent=1553"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/incentea.com\/cv\/en\/wp-json\/wp\/v2\/categories?post=1553"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/incentea.com\/cv\/en\/wp-json\/wp\/v2\/tags?post=1553"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}